{"id":6,"count":18,"description":"Guide pratiche per comprare auto, moto e veicoli usati senza fregature. Ti spieghiamo cosa controllare, quali documenti chiedere e come riconoscere un buon affare nel mercato dell'usato.","link":"https:\/\/usato.it\/notizie\/category\/motori\/","name":"Motori","slug":"motori","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/usato.it\/notizie\/wp-json\/wp\/v2\/categories\/6","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/usato.it\/notizie\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/usato.it\/notizie\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/usato.it\/notizie\/wp-json\/wp\/v2\/posts?categories=6"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}